{"id":1791,"date":"2018-12-10T14:20:27","date_gmt":"2018-12-10T19:20:27","guid":{"rendered":"https:\/\/paladinilaw.com\/aviso-cp504b-que-significa-y-como-responder\/"},"modified":"2026-03-10T08:59:52","modified_gmt":"2026-03-10T12:59:52","slug":"aviso-cp504b-que-significa-y-como-responder","status":"publish","type":"page","link":"https:\/\/paladinilaw.com\/es\/avisos-y-cartas-del-irs\/aviso-cp504b-que-significa-y-como-responder\/","title":{"rendered":"Aviso CP504B: qu\u00e9 significa y c\u00f3mo responder"},"content":{"rendered":"<p>Si va a recibir un aviso CP504B o CP504, significa que tiene una factura vencida con el IRS. Tambi\u00e9n significa que el IRS le ha enviado <a href=\"https:\/\/paladinilaw.com\/es\/avisos-y-cartas-del-irs\/\" target=\"_blank\" rel=\"noopener noreferrer\">cartas anteriormente<\/a> y usted no ha podido solucionar el problema, ya sea porque no puede pagar el saldo adeudado, porque disputa la deuda o porque no est\u00e1 seguro de c\u00f3mo solucionarlo. <\/p>\n<p>Sin embargo, no se deben ignorar las cartas de los avisos CP504 y CP504B. Es importante saber que usted tiene derechos legales que puede utilizar para evitar que el IRS le quite su dinero. Tambi\u00e9n cuenta con varios derechos procesales para establecer planes de pago o, posiblemente, incluso liquidar la deuda por un importe inferior.  <\/p>\n<h2>\u00bfQu\u00e9 significa el aviso CP504B?<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-315\" src=\"http:\/\/paladinilaw.com\/wp-content\/uploads\/2018\/12\/notice-cp504b.jpg\" alt=\"Aviso del IRS CP504B\" width=\"1275\" height=\"1650\" srcset=\"https:\/\/paladinilaw.com\/wp-content\/uploads\/2018\/12\/notice-cp504b.jpg 1275w, https:\/\/paladinilaw.com\/wp-content\/uploads\/2018\/12\/notice-cp504b-464x600.jpg 464w, https:\/\/paladinilaw.com\/wp-content\/uploads\/2018\/12\/notice-cp504b-768x994.jpg 768w, https:\/\/paladinilaw.com\/wp-content\/uploads\/2018\/12\/notice-cp504b-791x1024.jpg 791w\" sizes=\"auto, (max-width: 1275px) 100vw, 1275px\" \/><\/p>\n<p>Al enviar un aviso CP504B, el IRS est\u00e1 a un paso de cumplir los requisitos legales para embargar sus bienes personales, gravar su cuenta bancaria y detraer sus salarios. Si no se paga el saldo, el IRS comenzar\u00e1 a buscar activos sobre los cuales emitir un embargo. El IRS tambi\u00e9n puede presentar un Gravamen por Impuestos Federales si a\u00fan no se ha presentado uno. Es extremadamente dif\u00edcil pedir pr\u00e9stamos sobre una propiedad o venderla si existe un gravamen. Adem\u00e1s, dependiendo de su sector laboral y de sus licencias profesionales, un gravamen fiscal federal puede suponer un gran dolor de cabeza.    <\/p>\n<h2>No ignore al IRS: no hacer nada no cambia nada (y, de hecho, empeora las cosas)<\/h2>\n<p>Si no se pone en contacto con el IRS ni paga en un plazo de 30 d\u00edas, el IRS le enviar\u00e1 un aviso otorg\u00e1ndole el derecho a una audiencia ante la Oficina de Apelaciones del IRS (si no ha recibido ya dicho aviso). Este es uno de los avisos del IRS m\u00e1s importantes que recibir\u00e1 jam\u00e1s. Si no presenta una apelaci\u00f3n a tiempo, el IRS proceder\u00e1 a embargar sus bienes o los derechos sobre sus bienes. Los bienes que pueden ser gravados o embargados incluyen:   <\/p>\n<ul>\n<li>Salarios y otros ingresos<\/li>\n<li>Cuentas bancarias<\/li>\n<li>Activos comerciales<\/li>\n<li>Bienes personales (incluidos su coche y su vivienda)<\/li>\n<li>Reembolso de impuestos estatales<\/li>\n<li>Prestaciones de la seguridad social.<\/li>\n<\/ul>\n<h2>C\u00f3mo responder al aviso CP504B<\/h2>\n<p>Es importante hablar con un abogado fiscal experto antes de responder al IRS. Un abogado puede mantener correspondencia con el IRS y ayudarle a desarrollar una estrategia para evitar que la situaci\u00f3n se agrave. El primer paso para responder al aviso CP504B es ponerse en contacto con el IRS y apaciguar las gestiones de cobro para evitar embargos.  <\/p>\n<p>El siguiente paso en el proceso ser\u00e1 obtener las transcripciones de la cuenta del IRS. Si est\u00e1 de acuerdo con que debe lo que el IRS dice, su abogado puede ayudarle a dise\u00f1ar un plan para reducir o mitigar el impuesto. A menudo, la cantidad adeudada es objeto de disputa. Dependiendo de la situaci\u00f3n, es posible que pueda presentar declaraciones rectificativas para reducir la cantidad adeudada junto con una solicitud de reducci\u00f3n de sanciones.   <\/p>\n<h2>Hable con un abogado fiscal del IRS en Nueva Jersey<\/h2>\n<p>Si ha recibido el aviso CP504B y tiene preguntas o desea asesoramiento legal, p\u00f3ngase en contacto con Paladini Law llamando al (201) 381-4472 o <a href=\"https:\/\/paladinilaw.cliogrow.com\/book\/pAdZzq9YAy-BEObZ87l2qw\" target=\"_blank\" rel=\"noopener\">programe su consulta gratuita ahora<\/a>. El abogado Brad Paladini ha ayudado a contribuyentes de todo Nueva Jersey y del pa\u00eds a evitar sanciones y ahorrar miles de d\u00f3lares. El abogado Paladini puede revisar su caso, ayudarle a determinar si tiene sentido contratar a un abogado y trazar un plan de acci\u00f3n para resolver su problema fiscal.  <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si va a recibir un aviso CP504B o CP504, significa que tiene una factura vencida con el IRS. Tambi&eacute;n significa que el IRS le ha enviado cartas anteriormente y usted no ha podido solucionar el problema, ya sea porque no puede pagar el saldo adeudado, porque disputa la deuda o porque no est&aacute; seguro de [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":1794,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","footnotes":""},"class_list":["post-1791","page","type-page","status-publish","entry"],"acf":[],"featured_image_src":null,"featured_image_src_square":null,"_links":{"self":[{"href":"https:\/\/paladinilaw.com\/es\/wp-json\/wp\/v2\/pages\/1791","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/paladinilaw.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/paladinilaw.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/paladinilaw.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/paladinilaw.com\/es\/wp-json\/wp\/v2\/comments?post=1791"}],"version-history":[{"count":0,"href":"https:\/\/paladinilaw.com\/es\/wp-json\/wp\/v2\/pages\/1791\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/paladinilaw.com\/es\/wp-json\/wp\/v2\/pages\/1794"}],"wp:attachment":[{"href":"https:\/\/paladinilaw.com\/es\/wp-json\/wp\/v2\/media?parent=1791"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}